


{"id":9193,"date":"2016-10-10T07:54:08","date_gmt":"2016-10-10T07:54:08","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=9193"},"modified":"2021-11-04T19:36:51","modified_gmt":"2021-11-04T18:36:51","slug":"startup-rufa-partner-startup-lab-open-validation","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/es\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/","title":{"rendered":"Startup, RUFA \u00e8 partner di \u00abStartup Lab Open Validation\u00bb"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-es\">Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en <a href=\"http:\/\/3.66.171.122\/it\/wp-json\/wp\/v2\/posts\/9193\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"IT\">IT<\/a>.<\/p><h3>Al via il programma di formazione per far partire nuove imprese giovani e innovative<\/h3>\n<p>Quest&#8217;anno RUFA \u00e8 partner del programma della regione Lazio \u00abStartup Lab Open Validation &#8211; Sector Circular Economy\u00bb, finalizzato alla nascita di startup innovative che rispettano il concetto di sostenibilit\u00e0 dal punto di vista sociale, economico ed ambientale. Il percorso si avvarr\u00e0 della testimonianze di imprenditori ed operatori di eccellenza, con visite a significative realt\u00e0 imprenditoriali e scientifiche.<br \/>\nStartup, talenti e team imprenditoriali svilupperanno il proprio business in linea con i principi dell\u2019 economia circolare e sostenibile attraverso un percorso di ideazione, progettazione, sperimentazione e prototipazione. L&#8217;intero percorso durer\u00e0 6 settimane. I partecipanti saranno coinvolti in sessioni collaborative di co-design dove ognuno potr\u00e0 mettere a disposizione le proprie competenze all\u2019interno del gruppo e contribuire a sviluppare un\u2019idea creativa.<br \/>\nI progetti finalisti saranno giudicati e premiati in occasione dell\u2019 evento Isola della Sostenibilit\u00e0, manifestazione green legata al tema dell\u2019economia circolare in programma a Roma dall\u20198 al 10 dicembre 2016 presso il Salone delle Fontane.<br \/>\nOgni Startup avr\u00e0 10 minuti di tempo a disposizione, per uno speech di presentazione del proprio progetto anche con l\u2019ausilio di supporti multimediali.<br \/>\nPer partecipare collegarsi al seguente link:<a href=\"https:\/\/www.unirufa.it\/\" target=\"_blank\" rel=\"noopener noreferrer\"> http:\/\/www.biclazio.it\/it\/home\/al-via-startup-lab-open-validation-sector-circula.bic<\/a>.<br \/>","protected":false},"excerpt":{"rendered":"<p>Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT.Al via il programma di formazione per far partire nuove imprese giovani e innovative Quest&#8217;anno RUFA \u00e8 partner del programma della regione Lazio \u00abStartup Lab Open Validation &#8211; Sector Circular Economy\u00bb, finalizzato alla nascita di startup innovative che rispettano il concetto di sostenibilit\u00e0 dal punto di vista&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/es\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/\" title=\"Read Startup, RUFA \u00e8 partner di \u00abStartup Lab Open Validation\u00bb\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":9196,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31,951],"tags":[],"class_list":["post-9193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-news","category-bandi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Startup, RUFA \u00e8 partner di &quot;Startup Lab Open Validation&quot; - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Startup, RUFA \u00e8 partner di &quot;Startup Lab Open Validation&quot; - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT.Al via il programma di formazione per far partire nuove imprese giovani e innovative Quest&#8217;anno RUFA \u00e8 partner del programma della regione Lazio \u00abStartup Lab Open Validation &#8211; Sector Circular Economy\u00bb, finalizzato alla nascita di startup innovative che rispettano il concetto di sostenibilit\u00e0 dal punto di vista... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-10T07:54:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-04T18:36:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/10\/Startup-Lab-Open-Validation.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3300\" \/>\n\t<meta property=\"og:image:height\" content=\"2550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/\",\"url\":\"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/\",\"name\":\"Startup, RUFA \u00e8 partner di \\\"Startup Lab Open Validation\\\" - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"http:\/\/3.66.171.122:80\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/10\/Startup-Lab-Open-Validation.png\",\"datePublished\":\"2016-10-10T07:54:08+00:00\",\"dateModified\":\"2021-11-04T18:36:51+00:00\",\"author\":{\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/10\/Startup-Lab-Open-Validation.png\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/10\/Startup-Lab-Open-Validation.png\",\"width\":3300,\"height\":2550},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/3.66.171.122:80\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Startup, RUFA \u00e8 partner di &#8220;Startup Lab Open Validation&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#website\",\"url\":\"http:\/\/3.66.171.122:80\/en\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/3.66.171.122:80\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/es\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Startup, RUFA \u00e8 partner di \"Startup Lab Open Validation\" - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/","og_locale":"es_ES","og_type":"article","og_title":"Startup, RUFA \u00e8 partner di \"Startup Lab Open Validation\" - RUFA - Rome University of Fine Arts","og_description":"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT.Al via il programma di formazione per far partire nuove imprese giovani e innovative Quest&#8217;anno RUFA \u00e8 partner del programma della regione Lazio \u00abStartup Lab Open Validation &#8211; Sector Circular Economy\u00bb, finalizzato alla nascita di startup innovative che rispettano il concetto di sostenibilit\u00e0 dal punto di vista... Find out more","og_url":"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2016-10-10T07:54:08+00:00","article_modified_time":"2021-11-04T18:36:51+00:00","og_image":[{"width":3300,"height":2550,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/10\/Startup-Lab-Open-Validation.png","type":"image\/png"}],"author":"rufa","twitter_misc":{"Escrito por":"rufa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/","url":"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/","name":"Startup, RUFA \u00e8 partner di \"Startup Lab Open Validation\" - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"http:\/\/3.66.171.122:80\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/10\/Startup-Lab-Open-Validation.png","datePublished":"2016-10-10T07:54:08+00:00","dateModified":"2021-11-04T18:36:51+00:00","author":{"@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/10\/Startup-Lab-Open-Validation.png","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/10\/Startup-Lab-Open-Validation.png","width":3300,"height":2550},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/2016\/10\/10\/startup-rufa-partner-startup-lab-open-validation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/3.66.171.122:80\/en\/"},{"@type":"ListItem","position":2,"name":"Startup, RUFA \u00e8 partner di &#8220;Startup Lab Open Validation&#8221;"}]},{"@type":"WebSite","@id":"http:\/\/3.66.171.122:80\/en\/#website","url":"http:\/\/3.66.171.122:80\/en\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/3.66.171.122:80\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/es\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/9193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/comments?post=9193"}],"version-history":[{"count":3,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/9193\/revisions"}],"predecessor-version":[{"id":55338,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/9193\/revisions\/55338"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media\/9196"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media?parent=9193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/categories?post=9193"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/tags?post=9193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}