


{"id":9033,"date":"2016-09-23T10:10:16","date_gmt":"2016-09-23T10:10:16","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=9033"},"modified":"2020-08-08T11:04:29","modified_gmt":"2020-08-08T09:04:29","slug":"aperte-iscrizioni-premio-arte-laguna-2","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/es\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/","title":{"rendered":"Aperte le iscrizioni al Premio Arte Laguna"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-es\">Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en <a href=\"http:\/\/3.66.171.122\/it\/wp-json\/wp\/v2\/posts\/9033\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"IT\">IT<\/a> y <a href=\"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/9033\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"EN\">EN<\/a>.<\/p><h3>Le candidature possono essere inviate entro il 16 novembre. Grandi premi in palio, in denaro e non<\/h3>\n<p>Torna il Premio Arte Laguna, il prestigioso concorso artistico che d\u00e0 l&#8217;opportunit\u00e0 ai partecipanti di vincere importanti premi e di esporre all\u2019Arsenale di Venezia, uno dei luoghi pi\u00f9 ambiti dagli artisti e uno spazio di riferimento nel mondo dell\u2019arte contemporanea. La mostra avr\u00e0 inoltre una doppia sede sempre in laguna grazie alla prosecuzione della sinergia con TIM Future Centre che metter\u00e0 a disposizione gli spazi adiacenti a Rialto per la visione e interazione con le opere dedicate al digitale. Al concorso possono partecipare artisti da tutto il mondo senza alcuna limitazione o tema, l\u2019obiettivo \u00e8 quello di raccogliere e mappare l\u2019espressivit\u00e0 contemporanea dell\u2019arte negli ambiti di pittura, fotografia, scultura, video arte, performance, arte virtuale, land art a cui si aggiunge quest\u2019anno la grafica digitale, molteplicit\u00e0 che rende assolutamente unico il concorso nel panorama nazionale ed europeo. A selezionare i finalisti che salgono a 125 sar\u00e0 come sempre una giuria di esperti di calibro internazionale . <\/p>\n<p><strong>I PREMI <\/strong><br \/>\n<strong>Premi Artist in Residence<\/strong><br \/>\nSi tratta di un programma di residenze d\u2019arte in Italia e all\u2019estero allo scopo di offrire uno spazio e un tempo dove vivere l\u2019esperienza di una nuova cultura, creare nuove opere e partecipare a nuove attivit\u00e0 in un ambiente multiculturale. Sono 9 quest\u2019anno i partner: San Francisco Art Residency a cui collaborano tre realt\u00e0 Tech Shop, The Growlery, Pacific Felt Factory; The Art Department in Turchia, GLO\u2019ART in Belgio; Basu Foundation for the Arts a Calcutta, Espronceda a Barcellona; Taipei Artist Village; Serigrafia Artistica Fallani Venezia; Fondazione Berengo di Murano; Fonderia Salvadori Arte di Pistoia.<\/p>\n<p><strong>Premi Business for Art<\/strong><br \/>\nCollaborazioni con le aziende per la creazione di: una nuova collezione di borse e accessori marchiata Deglupta, azienda del veneziano; video promozionali, immagini per campagne pubblicitarie o design per le sedute d\u2019arredo con Rima Sofa &amp; Beds di Pordenone; una nuova interpretazione del prodotto papillon per una limited edition marchiata dall\u2019azienda napoletana Papillover; un video che valorizzi il rapporto arte-tecnologia attraverso una comunicazione unica e creativa con Eurosystem di Treviso; lo sviluppo di un network e l\u2019implementazione di servizi per l\u2019arte con la piattaforma canadese Biafarin. Ciascuna azienda premier\u00e0 l\u2019artista selezionato oltre che con una collaborazione anche con un premio in denaro per un totale di<strong> 17mila euro<\/strong>.<\/p>\n<p><strong>Premi Artist in Gallery<\/strong><br \/>\nRealizzazione di 5 mostre in Gallerie d\u2019Arte internazionali comprensive di allestimento, inaugurazione e catalogo presso: Salamatina Gallery a New York; Galerie Isabelle Lesmeister in Germania; Galeria Fernando Santos in Portogallo; ART re.FLEX Gallery a San Pietroburgo; Chelouche Gallery for Contemporary Art a Tel Aviv.<\/p>\n<p><strong>Partecipazioni a Festival e Mostre collettive<\/strong><br \/>\nSelezione di 12 artisti per la partecipazione ad eventi collettivi in Slovenia presso il Festival Art Stays, a Pechino con gli eventi organizzati da Art Nova 100 e a Venezia con l\u2019Esposizione Internazionale di Sculture e Installazioni &#8211; Open.<\/p>\n<p>Le candidature dovranno pervenire entro il 16 novembre 2016.<br \/>\nMaggiori informazioni e bando di concorso sono disponibili su <a href=\"http:\/\/www.premioartelaguna.it\" target=\"_blank\" rel=\"noopener noreferrer\">www.premioartelaguna.it<\/a><br \/>","protected":false},"excerpt":{"rendered":"<p>Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Le candidature possono essere inviate entro il 16 novembre. Grandi premi in palio, in denaro e non Torna il Premio Arte Laguna, il prestigioso concorso artistico che d\u00e0 l&#8217;opportunit\u00e0 ai partecipanti di vincere importanti premi e di esporre all\u2019Arsenale di Venezia, uno dei luoghi pi\u00f9&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/es\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/\" title=\"Read Aperte le iscrizioni al Premio Arte Laguna\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":9034,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31,951,1634,938,1641,937,1637],"tags":[],"class_list":["post-9033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-news","category-bandi","category-fotografia","category-graphic-design","category-multimedia-arts-and-design","category-pittura-scultura","category-scultura-e-installazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aperte le iscrizioni al Premio Arte Laguna - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aperte le iscrizioni al Premio Arte Laguna - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Le candidature possono essere inviate entro il 16 novembre. Grandi premi in palio, in denaro e non Torna il Premio Arte Laguna, il prestigioso concorso artistico che d\u00e0 l&#8217;opportunit\u00e0 ai partecipanti di vincere importanti premi e di esporre all\u2019Arsenale di Venezia, uno dei luoghi pi\u00f9... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-23T10:10:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-08T09:04:29+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/BANNER_BIG_IT.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"713\" \/>\n\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/\",\"url\":\"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/\",\"name\":\"Aperte le iscrizioni al Premio Arte Laguna - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"http:\/\/3.66.171.122:80\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/BANNER_BIG_IT.jpg\",\"datePublished\":\"2016-09-23T10:10:16+00:00\",\"dateModified\":\"2020-08-08T09:04:29+00:00\",\"author\":{\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/BANNER_BIG_IT.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/BANNER_BIG_IT.jpg\",\"width\":713,\"height\":367},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/3.66.171.122:80\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aperte le iscrizioni al Premio Arte Laguna\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#website\",\"url\":\"http:\/\/3.66.171.122:80\/en\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/3.66.171.122:80\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/es\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aperte le iscrizioni al Premio Arte Laguna - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/","og_locale":"es_ES","og_type":"article","og_title":"Aperte le iscrizioni al Premio Arte Laguna - RUFA - Rome University of Fine Arts","og_description":"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Le candidature possono essere inviate entro il 16 novembre. Grandi premi in palio, in denaro e non Torna il Premio Arte Laguna, il prestigioso concorso artistico che d\u00e0 l&#8217;opportunit\u00e0 ai partecipanti di vincere importanti premi e di esporre all\u2019Arsenale di Venezia, uno dei luoghi pi\u00f9... Find out more","og_url":"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2016-09-23T10:10:16+00:00","article_modified_time":"2020-08-08T09:04:29+00:00","og_image":[{"width":713,"height":367,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/BANNER_BIG_IT.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Escrito por":"rufa","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/","url":"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/","name":"Aperte le iscrizioni al Premio Arte Laguna - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"http:\/\/3.66.171.122:80\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/BANNER_BIG_IT.jpg","datePublished":"2016-09-23T10:10:16+00:00","dateModified":"2020-08-08T09:04:29+00:00","author":{"@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/BANNER_BIG_IT.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/BANNER_BIG_IT.jpg","width":713,"height":367},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/2016\/09\/23\/aperte-iscrizioni-premio-arte-laguna-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/3.66.171.122:80\/en\/"},{"@type":"ListItem","position":2,"name":"Aperte le iscrizioni al Premio Arte Laguna"}]},{"@type":"WebSite","@id":"http:\/\/3.66.171.122:80\/en\/#website","url":"http:\/\/3.66.171.122:80\/en\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/3.66.171.122:80\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/es\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/9033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/comments?post=9033"}],"version-history":[{"count":4,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/9033\/revisions"}],"predecessor-version":[{"id":31029,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/9033\/revisions\/31029"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media\/9034"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media?parent=9033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/categories?post=9033"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/tags?post=9033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}