


{"id":8824,"date":"2016-09-01T08:43:42","date_gmt":"2016-09-01T08:43:42","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=8824"},"modified":"2020-08-10T23:40:10","modified_gmt":"2020-08-10T21:40:10","slug":"workshop-montefiore-conca-volta-grande-esperienza-artistica","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/es\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/","title":{"rendered":"Workshop di Montefiore Conca, ancora una volta una grande esperienza artistica"},"content":{"rendered":"<h3>Gli studenti si sono cimentati con la creazione di teatrino Kamishibai<\/h3>\n<p>Anche quest&#8217;anno si \u00e8 svolto l&#8217;interessante workshop dedicato alla stampa d&#8217;artista, intitolato \u00abLa scatola magica\u00bb e svoltosi nella suggestiva cornice dll&#8217;Opificio della Rosa nel castello di Montefiore Conca, dal 2 al 13 luglio. Con il coordinamento dei docenti Maria Pina Bentivenga e Umberto Giovannini, cinque allievi della Rufa e cinque della Central Saint Martins si sono cimentati con la creazione di un teatrino Kamishibai con circa 10 tavole ciascuno, realizzato con tecniche miste e basic printmaking. Ogni allievo \u00e8 partito da una storia scelta e scritta da s\u00e9, procedendo attraverso l&#8217;analisi di spunti narrativi e analizzando la storia per punti anche attraverso il racconto di piccoli monologhi teatrali: \u00abIprimi giorni abbiamo alternato momenti dedicati alla progettazione a momenti dedicati alla narrazione \u2013 ha spiegato la docente Bentivenga \u2013 il terzo giorno abbiamo spinto ognuno degli allievi a narrare la storia attraverso l&#8217;uso di oggetti con la funzione di personaggi. Abbiamo cercato di metterli in una condizione di spaesamento, lontano dalle loro certezze per mandarli in direzioni diverse\u00bb.<\/p>\n<p>\u00ab\u00c8 stata un&#8217;esperienza meravigliosa per la sperimentazione tecnica, per lo scambio tra gli allievi, per la bellissima energia che si \u00e8 creata nel gruppo. Forse \u2013 ha concluso la docente \u2013 uno dei workshop pi\u00f9 interessanti e formativi a cui io abbia lavorato e da cui, seconfo me, gli allievi hanno appreso qualcosa di molto importante\u00bb. Il giorno dell&#8217;Open day, previsto il 17 settembre (per info <a href=\"http:\/\/www.unirufa.it\/evento\/arriva-open-day\/\" target=\"_blank\" rel=\"noopener noreferrer\">clicca qui<\/a>), sar\u00e0 possibile vedere i lavori di alcuni ragazzi, che racconteranno anche la loro testimonianza su questa esperienza molto formativa. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli studenti si sono cimentati con la creazione di teatrino Kamishibai Anche quest&#8217;anno si \u00e8 svolto l&#8217;interessante workshop dedicato alla stampa d&#8217;artista, intitolato \u00abLa scatola magica\u00bb e svoltosi nella suggestiva cornice dll&#8217;Opificio della Rosa nel castello di Montefiore Conca, dal 2 al 13 luglio. Con il coordinamento dei docenti Maria Pina Bentivenga e Umberto Giovannini,&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/es\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/\" title=\"Read Workshop di Montefiore Conca, ancora una volta una grande esperienza artistica\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":8851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31,934,937],"tags":[],"class_list":["post-8824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-news","category-didactics","category-pittura-scultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Workshop di Montefiore Conca, ancora una volta una grande esperienza artistica - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshop di Montefiore Conca, ancora una volta una grande esperienza artistica - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Gli studenti si sono cimentati con la creazione di teatrino Kamishibai Anche quest&#8217;anno si \u00e8 svolto l&#8217;interessante workshop dedicato alla stampa d&#8217;artista, intitolato \u00abLa scatola magica\u00bb e svoltosi nella suggestiva cornice dll&#8217;Opificio della Rosa nel castello di Montefiore Conca, dal 2 al 13 luglio. Con il coordinamento dei docenti Maria Pina Bentivenga e Umberto Giovannini,... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-01T08:43:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-10T21:40:10+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/Immagine-11.png\" \/>\n\t<meta property=\"og:image:width\" content=\"559\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/\",\"url\":\"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/\",\"name\":\"Workshop di Montefiore Conca, ancora una volta una grande esperienza artistica - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"http:\/\/3.66.171.122:80\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/Immagine-11.png\",\"datePublished\":\"2016-09-01T08:43:42+00:00\",\"dateModified\":\"2020-08-10T21:40:10+00:00\",\"author\":{\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/Immagine-11.png\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/Immagine-11.png\",\"width\":559,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/3.66.171.122:80\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workshop di Montefiore Conca, ancora una volta una grande esperienza artistica\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#website\",\"url\":\"http:\/\/3.66.171.122:80\/en\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/3.66.171.122:80\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/es\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workshop di Montefiore Conca, ancora una volta una grande esperienza artistica - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/","og_locale":"es_ES","og_type":"article","og_title":"Workshop di Montefiore Conca, ancora una volta una grande esperienza artistica - RUFA - Rome University of Fine Arts","og_description":"Gli studenti si sono cimentati con la creazione di teatrino Kamishibai Anche quest&#8217;anno si \u00e8 svolto l&#8217;interessante workshop dedicato alla stampa d&#8217;artista, intitolato \u00abLa scatola magica\u00bb e svoltosi nella suggestiva cornice dll&#8217;Opificio della Rosa nel castello di Montefiore Conca, dal 2 al 13 luglio. Con il coordinamento dei docenti Maria Pina Bentivenga e Umberto Giovannini,... Find out more","og_url":"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2016-09-01T08:43:42+00:00","article_modified_time":"2020-08-10T21:40:10+00:00","og_image":[{"width":559,"height":540,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/Immagine-11.png","type":"image\/png"}],"author":"rufa","twitter_misc":{"Escrito por":"rufa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/","url":"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/","name":"Workshop di Montefiore Conca, ancora una volta una grande esperienza artistica - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"http:\/\/3.66.171.122:80\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/Immagine-11.png","datePublished":"2016-09-01T08:43:42+00:00","dateModified":"2020-08-10T21:40:10+00:00","author":{"@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/Immagine-11.png","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2016\/09\/Immagine-11.png","width":559,"height":540},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/2016\/09\/01\/workshop-montefiore-conca-volta-grande-esperienza-artistica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/3.66.171.122:80\/en\/"},{"@type":"ListItem","position":2,"name":"Workshop di Montefiore Conca, ancora una volta una grande esperienza artistica"}]},{"@type":"WebSite","@id":"http:\/\/3.66.171.122:80\/en\/#website","url":"http:\/\/3.66.171.122:80\/en\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/3.66.171.122:80\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/es\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/8824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/comments?post=8824"}],"version-history":[{"count":5,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/8824\/revisions"}],"predecessor-version":[{"id":31051,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/8824\/revisions\/31051"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media\/8851"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media?parent=8824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/categories?post=8824"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/tags?post=8824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}