


{"id":6745,"date":"2015-12-22T08:52:42","date_gmt":"2015-12-22T08:52:42","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=6745"},"modified":"2021-11-02T18:12:24","modified_gmt":"2021-11-02T17:12:24","slug":"talk-de-finis-foto","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/es\/2015\/12\/22\/talk-de-finis-foto\/","title":{"rendered":"Il Talk con de Finis, le foto"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-es\">Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en <a href=\"http:\/\/3.66.171.122\/it\/wp-json\/wp\/v2\/posts\/6745\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"IT\">IT<\/a> y <a href=\"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/6745\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"EN\">EN<\/a>.<\/p><h3>Ecco gli scatti per rivivere l&#8217;incontro con il curatore romano<\/h3>\n<p>Mercoled\u00ec 16 dicembre all&#8217;Accademia RUFA si \u00e8 svolto il Talk con il curatore Giorgio de Finis. Un incontro interessante, ricco di stimoli avvincenti, incentrato su una nuova idea di museo, sdoganata dai paradigmi tradizionali, che lo vedono talvolta \u00abincastrato\u00bb tra vincoli burocratici e politici che ne condizionano la programmazione e che lo allontanano dal pubblico. Quello che propone de Finis \u00e8 un museo che interagisce con il pubblico, che trova nel pubblico la sua anima e il suo scopo culturale, sociale e artistico. E con questo spirito \u00e8 stato avviato il Maam a Roma e il Dif a Formello, uno dei primi musei diffusi d&#8217;Italia. Ecco le foto per rivivere l&#8217;incontro.","protected":false},"excerpt":{"rendered":"<p>Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Ecco gli scatti per rivivere l&#8217;incontro con il curatore romano Mercoled\u00ec 16 dicembre all&#8217;Accademia RUFA si \u00e8 svolto il Talk con il curatore Giorgio de Finis. Un incontro interessante, ricco di stimoli avvincenti, incentrato su una nuova idea di museo, sdoganata dai paradigmi tradizionali, che&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/es\/2015\/12\/22\/talk-de-finis-foto\/\" title=\"Read Il Talk con de Finis, le foto\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":6747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1629,31],"tags":[],"class_list":["post-6745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accademia","category-app-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il Talk con de Finis, le foto - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Talk con de Finis, le foto - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Ecco gli scatti per rivivere l&#8217;incontro con il curatore romano Mercoled\u00ec 16 dicembre all&#8217;Accademia RUFA si \u00e8 svolto il Talk con il curatore Giorgio de Finis. Un incontro interessante, ricco di stimoli avvincenti, incentrato su una nuova idea di museo, sdoganata dai paradigmi tradizionali, che... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-22T08:52:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-02T17:12:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/12\/giorgio_de_finis-rufa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/\",\"name\":\"Il Talk con de Finis, le foto - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/12\/giorgio_de_finis-rufa.jpg\",\"datePublished\":\"2015-12-22T08:52:42+00:00\",\"dateModified\":\"2021-11-02T17:12:24+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/12\/giorgio_de_finis-rufa.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/12\/giorgio_de_finis-rufa.jpg\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Talk con de Finis, le foto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/es\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Talk con de Finis, le foto - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/","og_locale":"es_ES","og_type":"article","og_title":"Il Talk con de Finis, le foto - RUFA - Rome University of Fine Arts","og_description":"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Ecco gli scatti per rivivere l&#8217;incontro con il curatore romano Mercoled\u00ec 16 dicembre all&#8217;Accademia RUFA si \u00e8 svolto il Talk con il curatore Giorgio de Finis. Un incontro interessante, ricco di stimoli avvincenti, incentrato su una nuova idea di museo, sdoganata dai paradigmi tradizionali, che... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-12-22T08:52:42+00:00","article_modified_time":"2021-11-02T17:12:24+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/12\/giorgio_de_finis-rufa.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Escrito por":"rufa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/","url":"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/","name":"Il Talk con de Finis, le foto - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/12\/giorgio_de_finis-rufa.jpg","datePublished":"2015-12-22T08:52:42+00:00","dateModified":"2021-11-02T17:12:24+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/12\/giorgio_de_finis-rufa.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/12\/giorgio_de_finis-rufa.jpg","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/12\/22\/talk-de-finis-foto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"Il Talk con de Finis, le foto"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/es\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/6745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/comments?post=6745"}],"version-history":[{"count":12,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/6745\/revisions"}],"predecessor-version":[{"id":55146,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/6745\/revisions\/55146"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media\/6747"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media?parent=6745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/categories?post=6745"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/tags?post=6745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}