


{"id":5571,"date":"2015-07-02T12:22:01","date_gmt":"2015-07-02T12:22:01","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=5571"},"modified":"2020-08-30T01:27:09","modified_gmt":"2020-08-29T23:27:09","slug":"road-to-crativity-sagmeister-in-rufa","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/es\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/","title":{"rendered":"Road to Creativity, Sagmeister in RUFA"},"content":{"rendered":"<h3>La prima edizione del RUFA Contest si \u00e8 conclusa con una grande serata, tra riflessioni, canti e balli<\/h3>\n<p>Venerd\u00ec 26 giugno al teatro Olimpico di Roma \u00e8 andato in scena il grande show \u201cRoad to creativity\u201d che ha visto come assoluto protagonista Stefan Sagmeister, il graphic designer coinvolto dall\u2019Accademia RUFA come giurato d\u2019onore del RUFA Contest 2015. Il pubblico ha risposto con grande entusiasmo alla chiamata, riempendo il teatro in ogni ordine di posto. Le aspettative, del resto, non sono state tradite: Sagmeister ha catturato l\u2019attenzione dei presenti per un\u2019ora intensa, in cui ha ripercorso la sua carriera, raccontando i suoi successi artistici e professionali. Il concept, come promesso, \u00e8 stato lo stesso che da anni l\u2019artista porta in giro per il mondo: the happyness. \u00abFelicit\u00e0, un argomento di cui parlo da molto tempo \u2013 ha detto l\u2019artista \u2013 nella nostra vita ci sono momenti di felicit\u00e0 intensi, altri meno intensi, o altri momenti che non finiscono mai, bisogna trovare quello che veramente ci rende felice per sempre\u00bb. Poi, rivolgendosi al pubblico ha continuato: \u00ab\u00c8 importante che siate qui non perch\u00e9 ci sono io ma perch\u00e9 non l\u2019avete fatto ieri e non lo farete domani. Fare cose diverse nella vita porta felicit\u00e0\u00bb. Una breve lezione di vita, un piccolo elogio alla felicit\u00e0, che Sagmeister ha illustrato servendosi di dati, oltre che di una lunga serie di immagini e video dal suo repertorio. E poi esposizioni, performance, lavori, sviluppati nel corso della sua carriera, con cui ha cercato da un lato di porre degli interrogativi alle persone e dall\u2019altro di mostrare il suo vissuto. Come i tre ingredienti che a detta sua possono fare la felicit\u00e0: ringraziamenti, umilt\u00e0, empatia simpatetica. E non \u00e8 mancato il canto. Sulle note dell\u2019inno alla gioia Sagmeister ha trasformato l\u2019intero teatro in un coro divertito e ironico, facendo da direttore d\u2019orchestra a un pubblico che intonava il suo inno alla felicit\u00e0, come se fosse una sigla dello spettacolo. E, per finire, il ballo. Al Lanificio di Roma la serata si \u00e8 conclusa a tarda notte con la comunit\u00e0 RUFA che, ancora una volta, ha dato prova del suo affiatamento e della sua vitalit\u00e0. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La prima edizione del RUFA Contest si \u00e8 conclusa con una grande serata, tra riflessioni, canti e balli Venerd\u00ec 26 giugno al teatro Olimpico di Roma \u00e8 andato in scena il grande show \u201cRoad to creativity\u201d che ha visto come assoluto protagonista Stefan Sagmeister, il graphic designer coinvolto dall\u2019Accademia RUFA come giurato d\u2019onore del RUFA&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/es\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/\" title=\"Read Road to Creativity, Sagmeister in RUFA\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":5577,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31,938],"tags":[],"class_list":["post-5571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-news","category-graphic-design"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Road to Creativity, Sagmeister in RUFA - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Road to Creativity, Sagmeister in RUFA - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"La prima edizione del RUFA Contest si \u00e8 conclusa con una grande serata, tra riflessioni, canti e balli Venerd\u00ec 26 giugno al teatro Olimpico di Roma \u00e8 andato in scena il grande show \u201cRoad to creativity\u201d che ha visto come assoluto protagonista Stefan Sagmeister, il graphic designer coinvolto dall\u2019Accademia RUFA come giurato d\u2019onore del RUFA... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-02T12:22:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-29T23:27:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/07\/sagmeister_news_web_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/\",\"name\":\"Road to Creativity, Sagmeister in RUFA - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/07\/sagmeister_news_web_2.jpg\",\"datePublished\":\"2015-07-02T12:22:01+00:00\",\"dateModified\":\"2020-08-29T23:27:09+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/07\/sagmeister_news_web_2.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/07\/sagmeister_news_web_2.jpg\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Road to Creativity, Sagmeister in RUFA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/es\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Road to Creativity, Sagmeister in RUFA - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/","og_locale":"es_ES","og_type":"article","og_title":"Road to Creativity, Sagmeister in RUFA - RUFA - Rome University of Fine Arts","og_description":"La prima edizione del RUFA Contest si \u00e8 conclusa con una grande serata, tra riflessioni, canti e balli Venerd\u00ec 26 giugno al teatro Olimpico di Roma \u00e8 andato in scena il grande show \u201cRoad to creativity\u201d che ha visto come assoluto protagonista Stefan Sagmeister, il graphic designer coinvolto dall\u2019Accademia RUFA come giurato d\u2019onore del RUFA... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-07-02T12:22:01+00:00","article_modified_time":"2020-08-29T23:27:09+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/07\/sagmeister_news_web_2.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Escrito por":"rufa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/","url":"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/","name":"Road to Creativity, Sagmeister in RUFA - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/07\/sagmeister_news_web_2.jpg","datePublished":"2015-07-02T12:22:01+00:00","dateModified":"2020-08-29T23:27:09+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/07\/sagmeister_news_web_2.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/07\/sagmeister_news_web_2.jpg","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/07\/02\/road-to-crativity-sagmeister-in-rufa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"Road to Creativity, Sagmeister in RUFA"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/es\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/comments?post=5571"}],"version-history":[{"count":5,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5571\/revisions"}],"predecessor-version":[{"id":31715,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5571\/revisions\/31715"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media\/5577"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media?parent=5571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/categories?post=5571"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/tags?post=5571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}