


{"id":5442,"date":"2015-05-27T08:59:53","date_gmt":"2015-05-27T08:59:53","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=5442"},"modified":"2021-11-04T19:44:09","modified_gmt":"2021-11-04T18:44:09","slug":"uscito-numero-insideart","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/es\/2015\/05\/27\/uscito-numero-insideart\/","title":{"rendered":"\u00c8 uscito il nuovo numero di Insideart"},"content":{"rendered":"<h3>La rivista di arte contemporanea, disponibile in libreria, si \u00e8 occupata anche di RUFA<\/h3>\n<p>\u00c8 uscito il nuovo numero di <strong>Insideart<\/strong>, il magazine internazionale di arte contemporanea pi\u00f9 diffuso tra gli addetti ai lavori e gli appassionati. Il giornale \u00e8 ricco di servizi di grande interesse: dagli approfondimenti sui migliori artisti del momento, tra cui anche tre nomi significativi legati a Rufa (due ex studenti: Francesca Leone e Simone Cametti; e Chiara Mu, che ha curato alcuni seminari) fino allo speciale sulla Biennale di Venezia, con i consigli sugli itinerari da seguire e le opinioni a firma di <strong>Ludovico Pratesi<\/strong> ed <strong>Ermanno Tedeschi<\/strong>. E poi il Focus sugli artisti italiani che stanno conquistando il mercato cinese, grandi nomi del calibro di <strong>Francesca Leone<\/strong>, <strong>Oliviero Rainaldi<\/strong> e <strong>Omar Galliani<\/strong>, con importanti ed esclusive interviste, per andare alla scoperta dei linguaggi di questi autorevoli interpreti della contemporaneit\u00e0. Per finire con un\u2019inchiesta sul nuovo fenomeno delle gallerie online, questo misterioso e promettente baluardo che si \u00e8 affacciato sul mercato dell\u2019arte: Insideart le ha \u201cstanate\u201d, le ha conosciute, ha visto il loro \u201dback end\u201d e racconta come lavorano e quali sfide si sono proposte. <\/p>\n<p>Con il nuovo numero, disponibile nelle librerie italiane e nei bookshop dei musei, l\u2019editore <strong>Guido Talarico<\/strong> lancia due novit\u00e0 editoriali: la <strong>copertina d\u2019artista<\/strong> e <strong>Insideart Gallery<\/strong>. La prima \u00e8 un\u2019iniziativa volta a valorizzare i pi\u00f9 talentuosi artisti della scena contemporanea. La nuova copertina \u00e8 stata realizzata, su commissione di Insideart, da <strong>Gianni Politi<\/strong>, uno degli artisti di punta del <strong>Pastificio Cerere di Roma<\/strong>.<br \/>\nLa seconda \u00e8 una piattaforma di vendita online di opere d\u2019arte, selezionate e garantite da Insideart. Si tratta di un sistema per dare ai lettori e agli appassionati l\u2019opportunit\u00e0 di fare un acquisto consapevole e di qualit\u00e0 generando, allo stesso tempo, un concreto sostegno agli artisti. Nella prima selezione, consultabile su <a href=\"http:\/\/insideart.eu\/artisti\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/insideart.eu\/artisti\/<\/a>  sono gi\u00e0 disponibili opere degli artisti trattati sul nuovo numero di Inside:<strong> Gianni Politi<\/strong>, con la sua copertina, <strong>Chiara Mu, Simone Cametti, Matteo Nasini, Giuseppe Lo Schiavo, Opiemme e Giovanni Troilo.<\/strong><br \/>\nTutti artisti affermati e conosciuti, che hanno sposato il progetto. L\u2019acquisto \u00e8 accompagnato da molte informazioni di approfondimento sugli artisti e il loro linguaggio ed \u00e8 seguito e assistito dalla redazione del giornale (date un\u2019occhiata a <a href=\"http:\/\/insideart.eu\/artisti\" target=\"_blank\" rel=\"noopener noreferrer\">Insideart Gallery<\/a>).<br \/>\nIl numero \u00e8 disponibile nelle librerie d\u2019Italia e nei i bookshop dei musei di arte contemporanea. Eccovi l\u2019elenco dei luoghi in cui acquistarlo: <a href=\"https:\/\/www.unirufa.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/insideart.eu\/dovetrovarci\/ <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La rivista di arte contemporanea, disponibile in libreria, si \u00e8 occupata anche di RUFA \u00c8 uscito il nuovo numero di Insideart, il magazine internazionale di arte contemporanea pi\u00f9 diffuso tra gli addetti ai lavori e gli appassionati. Il giornale \u00e8 ricco di servizi di grande interesse: dagli approfondimenti sui migliori artisti del momento, tra cui&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/es\/2015\/05\/27\/uscito-numero-insideart\/\" title=\"Read \u00c8 uscito il nuovo numero di Insideart\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":5443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1629,31],"tags":[],"class_list":["post-5442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accademia","category-app-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c8 uscito il nuovo numero di Insideart - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c8 uscito il nuovo numero di Insideart - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"La rivista di arte contemporanea, disponibile in libreria, si \u00e8 occupata anche di RUFA \u00c8 uscito il nuovo numero di Insideart, il magazine internazionale di arte contemporanea pi\u00f9 diffuso tra gli addetti ai lavori e gli appassionati. Il giornale \u00e8 ricco di servizi di grande interesse: dagli approfondimenti sui migliori artisti del momento, tra cui... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-27T08:59:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-04T18:44:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/05\/rufa_insideart_2015.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/\",\"name\":\"\u00c8 uscito il nuovo numero di Insideart - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/05\/rufa_insideart_2015.jpg\",\"datePublished\":\"2015-05-27T08:59:53+00:00\",\"dateModified\":\"2021-11-04T18:44:09+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/05\/rufa_insideart_2015.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/05\/rufa_insideart_2015.jpg\",\"width\":480,\"height\":601},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c8 uscito il nuovo numero di Insideart\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/es\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c8 uscito il nuovo numero di Insideart - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/","og_locale":"es_ES","og_type":"article","og_title":"\u00c8 uscito il nuovo numero di Insideart - RUFA - Rome University of Fine Arts","og_description":"La rivista di arte contemporanea, disponibile in libreria, si \u00e8 occupata anche di RUFA \u00c8 uscito il nuovo numero di Insideart, il magazine internazionale di arte contemporanea pi\u00f9 diffuso tra gli addetti ai lavori e gli appassionati. Il giornale \u00e8 ricco di servizi di grande interesse: dagli approfondimenti sui migliori artisti del momento, tra cui... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-05-27T08:59:53+00:00","article_modified_time":"2021-11-04T18:44:09+00:00","og_image":[{"width":480,"height":601,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/05\/rufa_insideart_2015.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Escrito por":"rufa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/","url":"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/","name":"\u00c8 uscito il nuovo numero di Insideart - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/05\/rufa_insideart_2015.jpg","datePublished":"2015-05-27T08:59:53+00:00","dateModified":"2021-11-04T18:44:09+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/05\/rufa_insideart_2015.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/05\/rufa_insideart_2015.jpg","width":480,"height":601},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/05\/27\/uscito-numero-insideart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"\u00c8 uscito il nuovo numero di Insideart"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/es\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/comments?post=5442"}],"version-history":[{"count":7,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5442\/revisions"}],"predecessor-version":[{"id":55342,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5442\/revisions\/55342"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media\/5443"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media?parent=5442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/categories?post=5442"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/tags?post=5442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}