


{"id":5232,"date":"2015-04-16T11:55:27","date_gmt":"2015-04-16T11:55:27","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=5232"},"modified":"2020-08-30T16:15:21","modified_gmt":"2020-08-30T14:15:21","slug":"libro-per-colonna-santa-2","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/es\/2015\/04\/16\/libro-per-colonna-santa-2\/","title":{"rendered":"Un libro per la Colonna santa"},"content":{"rendered":"<h3>Viene presentato venerd\u00ec e racconta la storia e il restauro del sostegno di marmo venerato per secoli<\/h3>\n<p>La Colonna santa \u00e8 il titolo del volume stampato dalle Edizioni capitolo vaticano. Il libro, presentato venerd\u00ec 17 aprile a palazzo Altieri alle 17.30, racconta le vicenda della Colonna, illustrando il suo recente restauro e la relativa campagna fotografica, con particolare riguardo alla tecnica di ripresa in luce ultravioletta, per la prima volta concepita come sussidio specifico a una ricerca epigrafica. Fra gli autori del volume troviamo anche Mallio Falcioni, docente Rufa di fotografia. La colonna santa \u00e8 datata fra il secondo e terzo secolo dopo Cristo ed \u00e8 stata venerata per millenni da milioni di pellegrini che lasciavano incisi i propri nomi sul fusto della colonna stessa nella credenza che Cristo si appoggiasse qui quando predicava al popolo ebraico. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viene presentato venerd\u00ec e racconta la storia e il restauro del sostegno di marmo venerato per secoli La Colonna santa \u00e8 il titolo del volume stampato dalle Edizioni capitolo vaticano. Il libro, presentato venerd\u00ec 17 aprile a palazzo Altieri alle 17.30, racconta le vicenda della Colonna, illustrando il suo recente restauro e la relativa campagna&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/es\/2015\/04\/16\/libro-per-colonna-santa-2\/\" title=\"Read Un libro per la Colonna santa\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":5227,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31,1637],"tags":[],"class_list":["post-5232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-news","category-scultura-e-installazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un libro per la Colonna santa - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un libro per la Colonna santa - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Viene presentato venerd\u00ec e racconta la storia e il restauro del sostegno di marmo venerato per secoli La Colonna santa \u00e8 il titolo del volume stampato dalle Edizioni capitolo vaticano. Il libro, presentato venerd\u00ec 17 aprile a palazzo Altieri alle 17.30, racconta le vicenda della Colonna, illustrando il suo recente restauro e la relativa campagna... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-16T11:55:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-30T14:15:21+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/colonna_santa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/\",\"name\":\"Un libro per la Colonna santa - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/colonna_santa.jpg\",\"datePublished\":\"2015-04-16T11:55:27+00:00\",\"dateModified\":\"2020-08-30T14:15:21+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/colonna_santa.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/colonna_santa.jpg\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un libro per la Colonna santa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/es\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un libro per la Colonna santa - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/","og_locale":"es_ES","og_type":"article","og_title":"Un libro per la Colonna santa - RUFA - Rome University of Fine Arts","og_description":"Viene presentato venerd\u00ec e racconta la storia e il restauro del sostegno di marmo venerato per secoli La Colonna santa \u00e8 il titolo del volume stampato dalle Edizioni capitolo vaticano. Il libro, presentato venerd\u00ec 17 aprile a palazzo Altieri alle 17.30, racconta le vicenda della Colonna, illustrando il suo recente restauro e la relativa campagna... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-04-16T11:55:27+00:00","article_modified_time":"2020-08-30T14:15:21+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/colonna_santa.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Escrito por":"rufa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/","url":"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/","name":"Un libro per la Colonna santa - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/colonna_santa.jpg","datePublished":"2015-04-16T11:55:27+00:00","dateModified":"2020-08-30T14:15:21+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/colonna_santa.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/colonna_santa.jpg","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/04\/16\/libro-per-colonna-santa-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"Un libro per la Colonna santa"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/es\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/comments?post=5232"}],"version-history":[{"count":2,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5232\/revisions"}],"predecessor-version":[{"id":31781,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5232\/revisions\/31781"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media\/5227"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media?parent=5232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/categories?post=5232"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/tags?post=5232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}