


{"id":5164,"date":"2015-03-30T11:31:12","date_gmt":"2015-03-30T11:31:12","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=5164"},"modified":"2020-08-30T16:18:27","modified_gmt":"2020-08-30T14:18:27","slug":"biennale-venezia-agevolazioni","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/es\/2015\/03\/30\/biennale-venezia-agevolazioni\/","title":{"rendered":"Biennale di Venezia, ecco le agevolazioni"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-es\">Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en <a href=\"http:\/\/3.66.171.122\/it\/wp-json\/wp\/v2\/posts\/5164\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"IT\">IT<\/a> y <a href=\"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5164\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"EN\">EN<\/a>.<\/p><h3>Pacchetti per docenti e studenti delle Accademie<\/h3>\n<p>Il 9 maggio 2015 apre al pubblico la 56esima Biennale di Venezia, dal titolo <em>All the World\u2019s Futures<\/em>, diretta da <strong>Okwui Enwezor<\/strong>. Per gli studenti e per i docenti delle Accademie di Belle arti sono disponibili alcune opportunit\u00e0. Si tratta di percorsi e programmi di approfondimento nell&#8217;ambito del progetto Biennale Sessions, che permette a gruppi di almeno 50 partecipanti  di stipulare delle convenzioni che prevedono dei benefit come speciali pass per visitare l\u2019esposizione per tre giorni consecutivi, al prezzo di 20\u20ac a partecipante; uno spazio gratuito per una presentazione o una sessione didattica auto-organizzata, all\u2019interno delle sedi espositive; la partecipazione gratuita allo speciale programma di workshop organizzati da Biennale; speciali condizioni di fruizione delle manifestazioni e iniziative concomitanti organizzate dai settori, danza, musica, teatro e cinema; packet lunch per gli stessi tre giorni alla tariffa agevolata di 7.00\u20ac presso i punti ristoro in sede espositiva; assistenza all\u2019organizzazione del soggiorno con operatori prequalificati dalla Biennale;  piano di promozione e comunicazione dedicato, con link ai siti delle Universit\u00e0 e Accademie convenzionate. <\/p>\n<p>Per maggiori informazioni rivolgetevi a biennale.sessions@labiennale.org o sessions@labiennale.org oppure chiamate i numeri  041.5218.734 \/ 041.2728.382.<\/p>","protected":false},"excerpt":{"rendered":"<p>Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Pacchetti per docenti e studenti delle Accademie Il 9 maggio 2015 apre al pubblico la 56esima Biennale di Venezia, dal titolo All the World\u2019s Futures, diretta da Okwui Enwezor. Per gli studenti e per i docenti delle Accademie di Belle arti sono disponibili alcune opportunit\u00e0&#8230;.  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/es\/2015\/03\/30\/biennale-venezia-agevolazioni\/\" title=\"Read Biennale di Venezia, ecco le agevolazioni\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":5165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1629,31],"tags":[],"class_list":["post-5164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accademia","category-app-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biennale di Venezia, ecco le agevolazioni - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biennale di Venezia, ecco le agevolazioni - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Pacchetti per docenti e studenti delle Accademie Il 9 maggio 2015 apre al pubblico la 56esima Biennale di Venezia, dal titolo All the World\u2019s Futures, diretta da Okwui Enwezor. Per gli studenti e per i docenti delle Accademie di Belle arti sono disponibili alcune opportunit\u00e0.... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-30T11:31:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-30T14:18:27+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_biennale_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/\",\"name\":\"Biennale di Venezia, ecco le agevolazioni - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_biennale_web.jpg\",\"datePublished\":\"2015-03-30T11:31:12+00:00\",\"dateModified\":\"2020-08-30T14:18:27+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_biennale_web.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_biennale_web.jpg\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biennale di Venezia, ecco le agevolazioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/es\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biennale di Venezia, ecco le agevolazioni - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/","og_locale":"es_ES","og_type":"article","og_title":"Biennale di Venezia, ecco le agevolazioni - RUFA - Rome University of Fine Arts","og_description":"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Pacchetti per docenti e studenti delle Accademie Il 9 maggio 2015 apre al pubblico la 56esima Biennale di Venezia, dal titolo All the World\u2019s Futures, diretta da Okwui Enwezor. Per gli studenti e per i docenti delle Accademie di Belle arti sono disponibili alcune opportunit\u00e0.... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-03-30T11:31:12+00:00","article_modified_time":"2020-08-30T14:18:27+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_biennale_web.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Escrito por":"rufa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/","url":"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/","name":"Biennale di Venezia, ecco le agevolazioni - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_biennale_web.jpg","datePublished":"2015-03-30T11:31:12+00:00","dateModified":"2020-08-30T14:18:27+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_biennale_web.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_biennale_web.jpg","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/03\/30\/biennale-venezia-agevolazioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"Biennale di Venezia, ecco le agevolazioni"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/es\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/comments?post=5164"}],"version-history":[{"count":3,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5164\/revisions"}],"predecessor-version":[{"id":31791,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/posts\/5164\/revisions\/31791"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media\/5165"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/media?parent=5164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/categories?post=5164"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/es\/wp-json\/wp\/v2\/tags?post=5164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}