


{"id":8868,"date":"2016-09-07T07:40:49","date_gmt":"2016-09-07T07:40:49","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=8868"},"modified":"2020-08-08T11:12:11","modified_gmt":"2020-08-08T09:12:11","slug":"mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/en\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/","title":{"rendered":"Mark Zuckerberg ha incontrato a Roma la founder dell&#8217;app &#8220;Le Cicogne&#8221;"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"http:\/\/3.66.171.122\/it\/wp-json\/wp\/v2\/posts\/8868\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"IT\">IT<\/a>.<\/p><h3>La start up \u00e8 stata lanciata da un team il cui Art director \u00e8 la nostra ex studentessa RUFA Ludovica Angeletti<\/h3>\n<p>Il 29 agosto scorso il Ceo di Facebook, il celebre Mark Zuckerberg \u00e8 stato a Roma, dove ha svolto una serie di incontri istituzionali, dal Papa a Renzi, fino ai giovani studenti della Luiss e agli imprenditori che hanno avviato delle smart start up. Tra loro c&#8217;era anche il gruppo di &#8220;Le Cicogne&#8221;, la diffusissima app dedicata alla ricerca delle baby sitter, il cui Art director \u00e8 l&#8217;ex studentessa RUFA di Graphic design Ludovica Angeletti. Si \u00e8 trattato di un incontro molto stimolante, ha raccontato Ludovica: &#8220;Eravamo rappresentati dalla nostra Ceo e founder Monica Archibugi, che ha spiegato a Mark la nostra intuizione e il nostro modello di business. Lui ci ha messo a disposizione il suo tempo per potergli fare delle richieste e suggerirci come migliorare i risultati utilizzando Facebook&#8221;. L&#8217;innovativa app, che ha spopolato in Italia, si proietta, quindi, in una dimensione internazionale. In bocca al lupo a Ludovica e alla sua squadra!","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in IT.La start up \u00e8 stata lanciata da un team il cui Art director \u00e8 la nostra ex studentessa RUFA Ludovica Angeletti Il 29 agosto scorso il Ceo di Facebook, il celebre Mark Zuckerberg \u00e8 stato a Roma, dove ha svolto una serie di incontri istituzionali, dal Papa a&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/en\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/\" title=\"Read Mark Zuckerberg ha incontrato a Roma la founder dell&#8217;app &#8220;Le Cicogne&#8221;\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31,938],"tags":[],"class_list":["post-8868","post","type-post","status-publish","format-standard","hentry","category-app-news","category-graphic-design"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mark Zuckerberg ha incontrato a Roma la founder dell&#039;app &quot;Le Cicogne&quot; - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mark Zuckerberg ha incontrato a Roma la founder dell&#039;app &quot;Le Cicogne&quot; - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in IT.La start up \u00e8 stata lanciata da un team il cui Art director \u00e8 la nostra ex studentessa RUFA Ludovica Angeletti Il 29 agosto scorso il Ceo di Facebook, il celebre Mark Zuckerberg \u00e8 stato a Roma, dove ha svolto una serie di incontri istituzionali, dal Papa a... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-07T07:40:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-08T09:12:11+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2017\/11\/logo-rufa-2016.png\" \/>\n\t<meta property=\"og:image:width\" content=\"230\" \/>\n\t<meta property=\"og:image:height\" content=\"149\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/\",\"url\":\"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/\",\"name\":\"Mark Zuckerberg ha incontrato a Roma la founder dell'app \\\"Le Cicogne\\\" - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"http:\/\/3.66.171.122:80\/en\/#website\"},\"datePublished\":\"2016-09-07T07:40:49+00:00\",\"dateModified\":\"2020-08-08T09:12:11+00:00\",\"author\":{\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/3.66.171.122:80\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mark Zuckerberg ha incontrato a Roma la founder dell&#8217;app &#8220;Le Cicogne&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#website\",\"url\":\"http:\/\/3.66.171.122:80\/en\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/3.66.171.122:80\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/en\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mark Zuckerberg ha incontrato a Roma la founder dell'app \"Le Cicogne\" - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/","og_locale":"en_US","og_type":"article","og_title":"Mark Zuckerberg ha incontrato a Roma la founder dell'app \"Le Cicogne\" - RUFA - Rome University of Fine Arts","og_description":"Sorry, this entry is only available in IT.La start up \u00e8 stata lanciata da un team il cui Art director \u00e8 la nostra ex studentessa RUFA Ludovica Angeletti Il 29 agosto scorso il Ceo di Facebook, il celebre Mark Zuckerberg \u00e8 stato a Roma, dove ha svolto una serie di incontri istituzionali, dal Papa a... Find out more","og_url":"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2016-09-07T07:40:49+00:00","article_modified_time":"2020-08-08T09:12:11+00:00","og_image":[{"width":230,"height":149,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2017\/11\/logo-rufa-2016.png","type":"image\/png"}],"author":"rufa","twitter_misc":{"Written by":"rufa","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/","url":"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/","name":"Mark Zuckerberg ha incontrato a Roma la founder dell'app \"Le Cicogne\" - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"http:\/\/3.66.171.122:80\/en\/#website"},"datePublished":"2016-09-07T07:40:49+00:00","dateModified":"2020-08-08T09:12:11+00:00","author":{"@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/2016\/09\/07\/mark-zuckenberg-incontrato-roma-founder-dellapp-cicogne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/3.66.171.122:80\/en\/"},{"@type":"ListItem","position":2,"name":"Mark Zuckerberg ha incontrato a Roma la founder dell&#8217;app &#8220;Le Cicogne&#8221;"}]},{"@type":"WebSite","@id":"http:\/\/3.66.171.122:80\/en\/#website","url":"http:\/\/3.66.171.122:80\/en\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/3.66.171.122:80\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/3.66.171.122:80\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/en\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/8868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/comments?post=8868"}],"version-history":[{"count":6,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/8868\/revisions"}],"predecessor-version":[{"id":31045,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/8868\/revisions\/31045"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media?parent=8868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/categories?post=8868"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/tags?post=8868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}