


{"id":5478,"date":"2015-06-04T14:25:09","date_gmt":"2015-06-04T14:25:09","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=5478"},"modified":"2020-08-30T01:34:19","modified_gmt":"2020-08-29T23:34:19","slug":"maker-faire-roma","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/","title":{"rendered":"Maker Faire a Roma"},"content":{"rendered":"<h3>C&#8217;\u00e8 ancora tempo fino al 15 giugno per partecipare alla pi\u00f9 grande fiera dedicata all&#8217;innovazione<\/h3>\n<p>C&#8217;\u00e8 tempo fino al 15 giugno per partecipare alla Maker Faire, uno dei pi\u00f9 importanti eventi internazionali dedicati all&#8217;innovazione. Una fiera che unisce scienza, fantascienza, tecnologia, divertimento e business per soddisfare un pubblico variegato di addetti al settore o semplicemente curiosi, di tutte le et\u00e0. Un momento di incontro, confronto, formazione e interazione che solo l&#8217;anno scorso ha registrato la partecipazione di circa 90mila visitatori e l&#8217;adesione di 600 progetti creativi e originali sviluppati nell&#8217;ambito di diversi settori. La sede principale della manifestazione \u00e8 Oltreoceno ma la versione europea si svolger\u00e0 a Roma dal 16 al 18 ottobre all&#8217;Universit\u00e0 La Sapienza che, per l&#8217;occasione, si trasformer\u00e0 in una vera e propria citt\u00e0 del futuro. La #Call4makers \u00e8 aperta anche agli studenti dell&#8217;Accademia che, entro il 15 giugno, potranno inviare i loro progetti che abbiano a che fare con la creativit\u00e0, l&#8217;interattivit\u00e0 e il design in senso lato.<\/p>\n<p><a href=\"http:\/\/www.makerfairerome.eu\/it\/call-for-makers\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sito Maker Fair<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&#8217;\u00e8 ancora tempo fino al 15 giugno per partecipare alla pi\u00f9 grande fiera dedicata all&#8217;innovazione C&#8217;\u00e8 tempo fino al 15 giugno per partecipare alla Maker Faire, uno dei pi\u00f9 importanti eventi internazionali dedicati all&#8217;innovazione. Una fiera che unisce scienza, fantascienza, tecnologia, divertimento e business per soddisfare un pubblico variegato di addetti al settore o semplicemente&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/\" title=\"Read Maker Faire a Roma\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":5479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1629,31],"tags":[],"class_list":["post-5478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accademia","category-app-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maker Faire a Roma - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maker Faire a Roma - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"C&#8217;\u00e8 ancora tempo fino al 15 giugno per partecipare alla pi\u00f9 grande fiera dedicata all&#8217;innovazione C&#8217;\u00e8 tempo fino al 15 giugno per partecipare alla Maker Faire, uno dei pi\u00f9 importanti eventi internazionali dedicati all&#8217;innovazione. Una fiera che unisce scienza, fantascienza, tecnologia, divertimento e business per soddisfare un pubblico variegato di addetti al settore o semplicemente... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-04T14:25:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-29T23:34:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/06\/makers_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/\",\"name\":\"Maker Faire a Roma - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/06\/makers_web.jpg\",\"datePublished\":\"2015-06-04T14:25:09+00:00\",\"dateModified\":\"2020-08-29T23:34:19+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/06\/makers_web.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/06\/makers_web.jpg\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maker Faire a Roma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/en\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maker Faire a Roma - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/","og_locale":"en_US","og_type":"article","og_title":"Maker Faire a Roma - RUFA - Rome University of Fine Arts","og_description":"C&#8217;\u00e8 ancora tempo fino al 15 giugno per partecipare alla pi\u00f9 grande fiera dedicata all&#8217;innovazione C&#8217;\u00e8 tempo fino al 15 giugno per partecipare alla Maker Faire, uno dei pi\u00f9 importanti eventi internazionali dedicati all&#8217;innovazione. Una fiera che unisce scienza, fantascienza, tecnologia, divertimento e business per soddisfare un pubblico variegato di addetti al settore o semplicemente... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-06-04T14:25:09+00:00","article_modified_time":"2020-08-29T23:34:19+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/06\/makers_web.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Written by":"rufa","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/","url":"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/","name":"Maker Faire a Roma - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/06\/makers_web.jpg","datePublished":"2015-06-04T14:25:09+00:00","dateModified":"2020-08-29T23:34:19+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/06\/makers_web.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/06\/makers_web.jpg","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/06\/04\/maker-faire-roma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"Maker Faire a Roma"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/en\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/comments?post=5478"}],"version-history":[{"count":3,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5478\/revisions"}],"predecessor-version":[{"id":31728,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5478\/revisions\/31728"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media\/5479"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media?parent=5478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/categories?post=5478"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/tags?post=5478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}