


{"id":5302,"date":"2015-04-28T11:52:51","date_gmt":"2015-04-28T11:52:51","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=5302"},"modified":"2020-08-30T16:12:07","modified_gmt":"2020-08-30T14:12:07","slug":"i-colori-luce-colori-pace","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/","title":{"rendered":"I colori della Luce, colori della Pace"},"content":{"rendered":"<h3>La grande personale di Karen Thomas, ex docente Rufa, nell\u2019ambito delle commemorazioni per la Prima guerra mondiale<\/h3>\n<p>\u201cIn generale, il colore \u00e8 un mezzo che consente di esercitare un influsso diretto sull\u2019anima. Il colore \u00e8 il tasto, l\u2019occhio, il martelletto, l\u2019anima il pianoforte dalle molte corde. L\u2019artista \u00e8 una mano che toccando questo o quel tasto mette in vibrazione l\u2019anima umana\u201d, cos\u00ec scriveva Wasily Kandinskji nel suo pi\u00f9 celebre scritto Lo spirituale nell\u2019arte. Da allora molto \u00e8 cambiato nell\u2019arte, ma il colore, per molti artisti, \u00e8 ancora la grammatica fondamentale per trasmettere un concetto, uno stato d\u2019animo. Karen Thomas, ex docente di tecniche pittoriche alla Rufa, nonch\u00e9 artista che ha alle spalle un lungo percorso pittorico caratterizzato da sperimentazioni materiche e da una profonda ricerca sul piano concettuale, \u00e8 proprio nell\u2019uso della luce e dei colori che trova la forza linguistica per comunicare il suo senso etico. A partire dal 9 maggio, difatti, nell\u2019ambito del Programma Ufficiale delle Commemorazioni del Centenario della Prima Guerra Mondiale, l\u2019artista, da sempre impegnata sul piano sociale, \u00e8 protagonista di una grande personale dal titolo <em>I colori della luce, colori della pace<\/em>, a cura dello storico dell\u2019arte Claudio Strinati, nel Polo Museale Franzenfeste di Fortezza in Alto Adige. E\u2019 in questa cornice, ricca di fascino e di storia, al confine tra l\u2019Italia e il resto dell\u2019Europa, che il significato culturale della mostra viene ancora di pi\u00f9 messo in luce: un discorso che attraversa nazioni e culture, per far riscoprire il valore dell\u2019unit\u00e0 e della coesione tra i popoli. In quest\u2019ottica di appartenenza all\u2019Unione Europea, anche l\u2019estetica dei dipinti, si carica di un valore etico e le forme, le ombre, i colori, si caricano di nuovi significati. Il Bianco, il Blu, il Giallo, ad esempio, sono per l\u2019artista strumenti per arrivare alla Pace, e anche il Nero, acquista per la Thomas un\u2019accezione positiva: \u00e8 il colore del caos, del buio, dal quale nasce la possibilit\u00e0 di riscatto, di rinascita, di luce. Quest\u2019alchimia cromatica trova le sue radici anche nel rapporto con la natura, una ricerca particolarmente cara all\u2019artista, in quanto presa di coscienza dell\u2019ambiente che ci circonda. \u201cOgni artista ha un compito etico \u2013 afferma la Thomas \u2013 l&#8217;opera d&#8217;arte, tra forme e colori, tra Luce e ombra, porta con se un forte messaggio e io come artista mi auguro che chi guarder\u00e0 i miei quadri possa sentire il mio messaggio di speranza e di Pace. Perch\u00e9 senza Pace non c\u2019\u00e8 Luce e senza Luce non c\u2019\u00e8 Pace\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La grande personale di Karen Thomas, ex docente Rufa, nell\u2019ambito delle commemorazioni per la Prima guerra mondiale \u201cIn generale, il colore \u00e8 un mezzo che consente di esercitare un influsso diretto sull\u2019anima. Il colore \u00e8 il tasto, l\u2019occhio, il martelletto, l\u2019anima il pianoforte dalle molte corde. L\u2019artista \u00e8 una mano che toccando questo o quel&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/\" title=\"Read I colori della Luce, colori della Pace\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":5303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31,937],"tags":[],"class_list":["post-5302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-news","category-pittura-scultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>I colori della Luce, colori della Pace - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I colori della Luce, colori della Pace - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"La grande personale di Karen Thomas, ex docente Rufa, nell\u2019ambito delle commemorazioni per la Prima guerra mondiale \u201cIn generale, il colore \u00e8 un mezzo che consente di esercitare un influsso diretto sull\u2019anima. Il colore \u00e8 il tasto, l\u2019occhio, il martelletto, l\u2019anima il pianoforte dalle molte corde. L\u2019artista \u00e8 una mano che toccando questo o quel... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-28T11:52:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-30T14:12:07+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/karen_thomas_rufa_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/\",\"name\":\"I colori della Luce, colori della Pace - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/karen_thomas_rufa_web.jpg\",\"datePublished\":\"2015-04-28T11:52:51+00:00\",\"dateModified\":\"2020-08-30T14:12:07+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/karen_thomas_rufa_web.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/karen_thomas_rufa_web.jpg\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I colori della Luce, colori della Pace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/en\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I colori della Luce, colori della Pace - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/","og_locale":"en_US","og_type":"article","og_title":"I colori della Luce, colori della Pace - RUFA - Rome University of Fine Arts","og_description":"La grande personale di Karen Thomas, ex docente Rufa, nell\u2019ambito delle commemorazioni per la Prima guerra mondiale \u201cIn generale, il colore \u00e8 un mezzo che consente di esercitare un influsso diretto sull\u2019anima. Il colore \u00e8 il tasto, l\u2019occhio, il martelletto, l\u2019anima il pianoforte dalle molte corde. L\u2019artista \u00e8 una mano che toccando questo o quel... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-04-28T11:52:51+00:00","article_modified_time":"2020-08-30T14:12:07+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/karen_thomas_rufa_web.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Written by":"rufa","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/","url":"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/","name":"I colori della Luce, colori della Pace - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/karen_thomas_rufa_web.jpg","datePublished":"2015-04-28T11:52:51+00:00","dateModified":"2020-08-30T14:12:07+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/karen_thomas_rufa_web.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/karen_thomas_rufa_web.jpg","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/04\/28\/i-colori-luce-colori-pace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"I colori della Luce, colori della Pace"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/en\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/comments?post=5302"}],"version-history":[{"count":4,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5302\/revisions"}],"predecessor-version":[{"id":31766,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5302\/revisions\/31766"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media\/5303"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media?parent=5302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/categories?post=5302"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/tags?post=5302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}