


{"id":5254,"date":"2015-04-21T07:53:54","date_gmt":"2015-04-21T07:53:54","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=5254"},"modified":"2020-08-30T16:14:37","modified_gmt":"2020-08-30T14:14:37","slug":"aracne-appuntamento-30-aprile","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/","title":{"rendered":"Aracne, nuovo appuntamento il 30 aprile"},"content":{"rendered":"<h3>Al Lanificio di Roma va in scena la nuova fase del contest di arti visive<\/h3>\n<p>Mancano pochi giorni alla nuova fase del concorso \u201cAracne \u2013 Arti per la citt\u00e0\u201d, il contest di arti visive rivolto ad artisti e creativi, a cura del Lanificio di Roma e realizzato grazie alla collaborazione con l\u2019Accademia RUFA. Il prossimo appuntamento \u00e8 in programma gioved\u00ec 30 aprile dalle 19 in poi. Nell\u2019occasione saranno esposte nuove opere che il pubblico potr\u00e0 giudicare e votare. Il concorso \u00e8 aperto a tutte le discipline, dalla pittura, alla fotografia fino alla scultura e all\u2019installazione. Nelle sezioni fotografia e scultura sono in gara molti talenti dell\u2019Accademia RUFA. I vincitori, come da regolamento, vedranno esposte le proprie creazioni in autorevoli sedi di rappresentanza diplomatica. La fase di gioved\u00ec, in particolare, \u00e8 promossa dall\u2019Ambasciata di Francia, che presenter\u00e0 al pubblico, nell\u2019ambito della stessa serata, anche il famoso festival musicale Paris Rockin. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al Lanificio di Roma va in scena la nuova fase del contest di arti visive Mancano pochi giorni alla nuova fase del concorso \u201cAracne \u2013 Arti per la citt\u00e0\u201d, il contest di arti visive rivolto ad artisti e creativi, a cura del Lanificio di Roma e realizzato grazie alla collaborazione con l\u2019Accademia RUFA. Il prossimo&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/\" title=\"Read Aracne, nuovo appuntamento il 30 aprile\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":5255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31,951,937],"tags":[],"class_list":["post-5254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-news","category-bandi","category-pittura-scultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aracne, nuovo appuntamento il 30 aprile - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aracne, nuovo appuntamento il 30 aprile - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Al Lanificio di Roma va in scena la nuova fase del contest di arti visive Mancano pochi giorni alla nuova fase del concorso \u201cAracne \u2013 Arti per la citt\u00e0\u201d, il contest di arti visive rivolto ad artisti e creativi, a cura del Lanificio di Roma e realizzato grazie alla collaborazione con l\u2019Accademia RUFA. Il prossimo... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-21T07:53:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-30T14:14:37+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/aracne_contest_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/\",\"name\":\"Aracne, nuovo appuntamento il 30 aprile - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/aracne_contest_web.jpg\",\"datePublished\":\"2015-04-21T07:53:54+00:00\",\"dateModified\":\"2020-08-30T14:14:37+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/aracne_contest_web.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/aracne_contest_web.jpg\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aracne, nuovo appuntamento il 30 aprile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/en\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aracne, nuovo appuntamento il 30 aprile - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/","og_locale":"en_US","og_type":"article","og_title":"Aracne, nuovo appuntamento il 30 aprile - RUFA - Rome University of Fine Arts","og_description":"Al Lanificio di Roma va in scena la nuova fase del contest di arti visive Mancano pochi giorni alla nuova fase del concorso \u201cAracne \u2013 Arti per la citt\u00e0\u201d, il contest di arti visive rivolto ad artisti e creativi, a cura del Lanificio di Roma e realizzato grazie alla collaborazione con l\u2019Accademia RUFA. Il prossimo... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-04-21T07:53:54+00:00","article_modified_time":"2020-08-30T14:14:37+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/aracne_contest_web.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Written by":"rufa","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/","url":"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/","name":"Aracne, nuovo appuntamento il 30 aprile - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/aracne_contest_web.jpg","datePublished":"2015-04-21T07:53:54+00:00","dateModified":"2020-08-30T14:14:37+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/aracne_contest_web.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/04\/aracne_contest_web.jpg","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/04\/21\/aracne-appuntamento-30-aprile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"Aracne, nuovo appuntamento il 30 aprile"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/en\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/comments?post=5254"}],"version-history":[{"count":3,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5254\/revisions"}],"predecessor-version":[{"id":31777,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5254\/revisions\/31777"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media\/5255"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media?parent=5254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/categories?post=5254"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/tags?post=5254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}