


{"id":5099,"date":"2015-03-24T12:14:36","date_gmt":"2015-03-24T12:14:36","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=5099"},"modified":"2015-03-25T12:52:17","modified_gmt":"2015-03-25T12:52:17","slug":"rufa-ospita-luniversita-malese","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/","title":{"rendered":"Rufa ospita l&#8217;universit\u00e0 malese"},"content":{"rendered":"<p><\/p>\n<h3>Le responsabili del Kdu University College arrivano a Roma per rinnovare l&#8217;accordo con l&#8217;accademia<\/h3>\n<p>In virt\u00f9 dell\u2019accordo siglato da Rufa con il Kdu University College di Petaling Jaya, in Malesia, il 23 e il 24 marzo sono ospiti dell&#8217;accademia romana la vicepresidente dell\u2019accademia malese, professoressa Hon Wei Min, e la direttrice del dipartimento di arti visive, Pouline Koh. Un\u2019occasione utile non soltanto a mostrare alle due rappresentanti dell\u2019istituzione malese gli spazi e gli strumenti di lavoro dell&#8217;accademia romana, ma anche per dare avvio uno scambio culturale destinato a produrre iniziative culturali proficue. \u00abStanno cambiando molto le cose negli ultimi tempi, soprattutto nel settore del privato. In Malesia l\u2019offerta didattica \u00e8 pi\u00f9 tradizionale e punta pi\u00f9 sul fornire agli studenti una forte conoscenza teorica \u2013 spiega la vicepresidente \u2013 questo per\u00f2 va a discapito della formazione pratica, che in alcuni casi risulta carente. Risultato? Gli studenti non sono preparati a fronteggiare il mondo del lavoro\u00bb. L\u2019idea di una sinergia con Rufa nasce quindi anche dalla necessit\u00e0 di sopperire a questa mancanza di offerta che, rivela Hon Wei Min, potrebbe essere colmata grazie all\u2019introduzione di un master in design. \u00abVisual and Innovation design \u2013 puntualizza \u2013 abbiamo bisogno anche di muoverci verso le nuove tecnologie e, dopo aver visitato i vostri laboratori, siamo rimaste davvero colpite. In Malesia abbiamo tante idee, ma a volte, abbiamo strumenti molto basilari per realizzarle\u00bb. Con l\u2019implemento dei corsi di design, inoltre, si cercher\u00e0 di smentire l\u2019idea che lo studio del design rende pi\u00f9 difficile la ricerca di un lavoro: \u00abI giovani studenti in Malesia sono spesso poco incoraggiati a imboccare questa strada, perch\u00e9 c\u2019\u00e8 la convinzione che non si possa intraprendere una carriera professionale con il design\u00bb. Una convinzione, a detta loro, assolutamente sbagliata, specie in una cultura che sta facendo dell\u2019arte una vera e propria risorsa identitaria: \u00abAbbiamo una produzione artistica molto florida \u2013 afferma Pouline Koh \u2013 i nostri creativi guardano a Ovest, \u00e8 ovvio, specie alla Francia, ma una forte stimolo deriva soprattutto dalla nostra tradizione orientale, specie da quella cinese\u00bb.<br \/>\nCompenetrazione tra tradizione antica e contemporanea: questo \u00e8 uno degli elementi di forza che la cultura capitolina condivide con quella malese. Ma non \u00e8 tutto. Se c\u2019\u00e8 un elemento su cui Rufa e Kdu university college sono d\u2019accordo \u00e8 la grande apertura verso nuove possibilit\u00e0 che pu\u00f2 derivare da questa collaborazione. Un\u2019occasione di crescita e di cambiamento sia per gli studenti che per le stesse accademie: \u00abCrediamo fermamente \u2013 sostiene Hon Wei Min \u2013 che i nostri studenti possano imparare molte cose e farne tesoro, portandole nel nostro paese. Abbiamo due culture molto antiche, con uno spirito artistico altrettanto forte, e dal loro incontro e dalla loro fusione, possono nascere idee molto positive. Noi crediamo in voi e voi credete in noi\u00bb.<br \/>\nQuale miglior modo per cominciare questo percorso?<\/p>","protected":false},"excerpt":{"rendered":"<p>Le responsabili del Kdu University College arrivano a Roma per rinnovare l&#8217;accordo con l&#8217;accademia In virt\u00f9 dell\u2019accordo siglato da Rufa con il Kdu University College di Petaling Jaya, in Malesia, il 23 e il 24 marzo sono ospiti dell&#8217;accademia romana la vicepresidente dell\u2019accademia malese, professoressa Hon Wei Min, e la direttrice del dipartimento di arti&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/\" title=\"Read Rufa ospita l&#8217;universit\u00e0 malese\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":5101,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31],"tags":[],"class_list":["post-5099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rufa ospita l&#039;universit\u00e0 malese - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rufa ospita l&#039;universit\u00e0 malese - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Le responsabili del Kdu University College arrivano a Roma per rinnovare l&#8217;accordo con l&#8217;accademia In virt\u00f9 dell\u2019accordo siglato da Rufa con il Kdu University College di Petaling Jaya, in Malesia, il 23 e il 24 marzo sono ospiti dell&#8217;accademia romana la vicepresidente dell\u2019accademia malese, professoressa Hon Wei Min, e la direttrice del dipartimento di arti... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-24T12:14:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-03-25T12:52:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_delegazione_malese_240315.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/\",\"name\":\"Rufa ospita l'universit\u00e0 malese - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_delegazione_malese_240315.jpg\",\"datePublished\":\"2015-03-24T12:14:36+00:00\",\"dateModified\":\"2015-03-25T12:52:17+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_delegazione_malese_240315.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_delegazione_malese_240315.jpg\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rufa ospita l&#8217;universit\u00e0 malese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/en\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rufa ospita l'universit\u00e0 malese - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/","og_locale":"en_US","og_type":"article","og_title":"Rufa ospita l'universit\u00e0 malese - RUFA - Rome University of Fine Arts","og_description":"Le responsabili del Kdu University College arrivano a Roma per rinnovare l&#8217;accordo con l&#8217;accademia In virt\u00f9 dell\u2019accordo siglato da Rufa con il Kdu University College di Petaling Jaya, in Malesia, il 23 e il 24 marzo sono ospiti dell&#8217;accademia romana la vicepresidente dell\u2019accademia malese, professoressa Hon Wei Min, e la direttrice del dipartimento di arti... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-03-24T12:14:36+00:00","article_modified_time":"2015-03-25T12:52:17+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_delegazione_malese_240315.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Written by":"rufa","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/","url":"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/","name":"Rufa ospita l'universit\u00e0 malese - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_delegazione_malese_240315.jpg","datePublished":"2015-03-24T12:14:36+00:00","dateModified":"2015-03-25T12:52:17+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_delegazione_malese_240315.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/03\/rufa_delegazione_malese_240315.jpg","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/03\/24\/rufa-ospita-luniversita-malese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"Rufa ospita l&#8217;universit\u00e0 malese"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/en\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/comments?post=5099"}],"version-history":[{"count":3,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5099\/revisions"}],"predecessor-version":[{"id":5103,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/5099\/revisions\/5103"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media\/5101"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media?parent=5099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/categories?post=5099"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/tags?post=5099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}