


{"id":4967,"date":"2015-02-23T11:39:17","date_gmt":"2015-02-23T11:39:17","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=4967"},"modified":"2021-10-29T17:31:34","modified_gmt":"2021-10-29T15:31:34","slug":"cinema-pronto-bando-dellacademy-of-arts-film-festival","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/","title":{"rendered":"Cinema, pronto il bando dell\u2019Academy of Fine Arts Film Festival"},"content":{"rendered":"<h3>Il premio dedicato ai giovani cineasti<\/h3>\n<p>Sono aperte le iscrizioni all\u2019Academy of Fine Arts Film Festival, organizzato dall\u2019Accademia di Belle Arti di Napoli, diretto a promuovere e diffondere i lavori audiovisivi realizzati dagli studenti delle Accademie di Belle Arti italiane ed europee. Nel corso della selezione saranno scelti i prodotti ritenuti pi\u00f9 validi, che saranno poi proiettati durante la manifestazione finale del contest, in programma a Napoli nel mese di giugno. Le premiazioni saranno tante: si va dal miglior film e regia, all\u2019attestato alla migliore sceneggiatura, fino agli altri riconoscimenti, come l\u2019attestato alla migliore fotografia, l\u2019attestato al miglior montaggio, l\u2019attestato alla migliore scenografia, l\u2019attestato ai migliori costumi e al Premio Digigraf 25.0 (riservato agli studenti dell\u2019Accademia di Belle Arti di Napoli). Il vincitore del premio \u201cmiglior film e regia\u201d sar\u00e0 ospitato per tre giorni, a spese dell\u2019Accademia, a Napoli durante il periodo della manifestazione, e gli saranno consegnati un\u2019opera realizzata dagli allievi del corso di Scultura del professor Vitagliano e la somma di \u20ac 500,00.<\/p>\n<p><a href=\"https:\/\/www.unirufa.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Scarica il Bando<\/a>","protected":false},"excerpt":{"rendered":"<p>Il premio dedicato ai giovani cineasti Sono aperte le iscrizioni all\u2019Academy of Fine Arts Film Festival, organizzato dall\u2019Accademia di Belle Arti di Napoli, diretto a promuovere e diffondere i lavori audiovisivi realizzati dagli studenti delle Accademie di Belle Arti italiane ed europee. Nel corso della selezione saranno scelti i prodotti ritenuti pi\u00f9 validi, che saranno&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/\" title=\"Read Cinema, pronto il bando dell\u2019Academy of Fine Arts Film Festival\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":4968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31,951,940],"tags":[],"class_list":["post-4967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-news","category-bandi","category-cinema-photography"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cinema, pronto il bando dell\u2019Academy of Fine Arts Film Festival - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinema, pronto il bando dell\u2019Academy of Fine Arts Film Festival - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Il premio dedicato ai giovani cineasti Sono aperte le iscrizioni all\u2019Academy of Fine Arts Film Festival, organizzato dall\u2019Accademia di Belle Arti di Napoli, diretto a promuovere e diffondere i lavori audiovisivi realizzati dagli studenti delle Accademie di Belle Arti italiane ed europee. Nel corso della selezione saranno scelti i prodotti ritenuti pi\u00f9 validi, che saranno... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-23T11:39:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-29T15:31:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/film-arts-festival.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/\",\"name\":\"Cinema, pronto il bando dell\u2019Academy of Fine Arts Film Festival - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/film-arts-festival.jpg\",\"datePublished\":\"2015-02-23T11:39:17+00:00\",\"dateModified\":\"2021-10-29T15:31:34+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/film-arts-festival.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/film-arts-festival.jpg\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cinema, pronto il bando dell\u2019Academy of Fine Arts Film Festival\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/en\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinema, pronto il bando dell\u2019Academy of Fine Arts Film Festival - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/","og_locale":"en_US","og_type":"article","og_title":"Cinema, pronto il bando dell\u2019Academy of Fine Arts Film Festival - RUFA - Rome University of Fine Arts","og_description":"Il premio dedicato ai giovani cineasti Sono aperte le iscrizioni all\u2019Academy of Fine Arts Film Festival, organizzato dall\u2019Accademia di Belle Arti di Napoli, diretto a promuovere e diffondere i lavori audiovisivi realizzati dagli studenti delle Accademie di Belle Arti italiane ed europee. Nel corso della selezione saranno scelti i prodotti ritenuti pi\u00f9 validi, che saranno... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-02-23T11:39:17+00:00","article_modified_time":"2021-10-29T15:31:34+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/film-arts-festival.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Written by":"rufa","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/","url":"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/","name":"Cinema, pronto il bando dell\u2019Academy of Fine Arts Film Festival - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/film-arts-festival.jpg","datePublished":"2015-02-23T11:39:17+00:00","dateModified":"2021-10-29T15:31:34+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/film-arts-festival.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/film-arts-festival.jpg","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/02\/23\/cinema-pronto-bando-dellacademy-of-arts-film-festival\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"Cinema, pronto il bando dell\u2019Academy of Fine Arts Film Festival"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/en\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/comments?post=4967"}],"version-history":[{"count":4,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4967\/revisions"}],"predecessor-version":[{"id":54991,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4967\/revisions\/54991"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media\/4968"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media?parent=4967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/categories?post=4967"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/tags?post=4967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}