


{"id":4840,"date":"2015-02-10T10:30:09","date_gmt":"2015-02-10T10:30:09","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=4840"},"modified":"2021-10-28T10:51:57","modified_gmt":"2021-10-28T08:51:57","slug":"video-allexpo-2015","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/","title":{"rendered":"Un vostro video all\u2019Expo 2015"},"content":{"rendered":"<h3>Lanciato un bando per video artisti con la possibilit\u00e0 di esporre nell\u2019evento milanese<\/h3>\n<p>Lanciato il concorso per partecipare alla mostra \u201cCibo per gli occhi\u201d con la possibilit\u00e0 di vedere esposti i propri lavori anche all\u2019interno dell\u2019Expo milanese. Il bando \u00e8 rivolto a video artisti invitati a interpretare 11 prodotti tipici legati all\u2019alimentazione irpina. Undici corti, ognuno legato a una specialit\u00e0 gastronomica di una zona diversa dell\u2019Irpinia e tre premi finali, il primo dei quali consiste nell\u2019inserimento del vincitore sul portale Bin-uiq, promotore dell\u2019evento, e nella presentazione all\u2019interno della mostra \u201cCibo con gli occhi\u201d. Per il secondo e il terzo classificato ci sar\u00e0 la possibilit\u00e0 di esporre nella mostra. I video selezionati inoltre saranno proiettati nello stand Giffoni di Expo 2015.<\/p>\n<p><a href=\"https:\/\/www.unirufa.it\/en\/\" target=\"_blank\" rel=\"noopener noreferrer\">Scarica il bando.<\/a>","protected":false},"excerpt":{"rendered":"<p>Lanciato un bando per video artisti con la possibilit\u00e0 di esporre nell\u2019evento milanese Lanciato il concorso per partecipare alla mostra \u201cCibo per gli occhi\u201d con la possibilit\u00e0 di vedere esposti i propri lavori anche all\u2019interno dell\u2019Expo milanese. Il bando \u00e8 rivolto a video artisti invitati a interpretare 11 prodotti tipici legati all\u2019alimentazione irpina. Undici corti,&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/\" title=\"Read Un vostro video all\u2019Expo 2015\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":4841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31,951,940],"tags":[],"class_list":["post-4840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-news","category-bandi","category-cinema-photography"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un vostro video all\u2019Expo 2015 - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un vostro video all\u2019Expo 2015 - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Lanciato un bando per video artisti con la possibilit\u00e0 di esporre nell\u2019evento milanese Lanciato il concorso per partecipare alla mostra \u201cCibo per gli occhi\u201d con la possibilit\u00e0 di vedere esposti i propri lavori anche all\u2019interno dell\u2019Expo milanese. Il bando \u00e8 rivolto a video artisti invitati a interpretare 11 prodotti tipici legati all\u2019alimentazione irpina. Undici corti,... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-10T10:30:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-28T08:51:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/cibo-occhi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/\",\"name\":\"Un vostro video all\u2019Expo 2015 - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/cibo-occhi.jpg\",\"datePublished\":\"2015-02-10T10:30:09+00:00\",\"dateModified\":\"2021-10-28T08:51:57+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/cibo-occhi.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/cibo-occhi.jpg\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un vostro video all\u2019Expo 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/en\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un vostro video all\u2019Expo 2015 - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/","og_locale":"en_US","og_type":"article","og_title":"Un vostro video all\u2019Expo 2015 - RUFA - Rome University of Fine Arts","og_description":"Lanciato un bando per video artisti con la possibilit\u00e0 di esporre nell\u2019evento milanese Lanciato il concorso per partecipare alla mostra \u201cCibo per gli occhi\u201d con la possibilit\u00e0 di vedere esposti i propri lavori anche all\u2019interno dell\u2019Expo milanese. Il bando \u00e8 rivolto a video artisti invitati a interpretare 11 prodotti tipici legati all\u2019alimentazione irpina. Undici corti,... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-02-10T10:30:09+00:00","article_modified_time":"2021-10-28T08:51:57+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/cibo-occhi.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Written by":"rufa","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/","url":"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/","name":"Un vostro video all\u2019Expo 2015 - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/cibo-occhi.jpg","datePublished":"2015-02-10T10:30:09+00:00","dateModified":"2021-10-28T08:51:57+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/cibo-occhi.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/cibo-occhi.jpg","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/02\/10\/video-allexpo-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"Un vostro video all\u2019Expo 2015"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/en\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/comments?post=4840"}],"version-history":[{"count":8,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4840\/revisions"}],"predecessor-version":[{"id":54824,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4840\/revisions\/54824"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media\/4841"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media?parent=4840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/categories?post=4840"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/tags?post=4840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}