


{"id":4761,"date":"2015-02-02T10:49:30","date_gmt":"2015-02-02T10:49:30","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=4761"},"modified":"2020-08-30T16:28:58","modified_gmt":"2020-08-30T14:28:58","slug":"michelangelo-lupone-gnam-rende-tangibile-suono","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/","title":{"rendered":"Michelangelo Lupone alla Gnam rende tangibile il suono"},"content":{"rendered":"<h3>Un&#8217;installazione multisensoriale, concepita in collaborazione con Rufa<\/h3>\n<p>Il 6 febbraio la Galleria Nazionale d&#8217;Arte Moderna e contemporanea di Roma inaugura <em>Forme immateriali del compositore Michelangelo Lupone<\/em>, un&#8217;opera complessa che nasce dal connubio tra arte e musica, commissionata direttamente dalla GNAM per dialogare con l&#8217;architettura circostante ed essere inglobata nella collezione permanente del museo. Martina De Luca \u00e8 curatore del progetto, concepito appositamente per le due fontane del Cortile del Partigiano e pensato,grazie al suo aspetto interattivo, per essere attivato dal pubblico. Quest&#8217;ultimo infatti \u00e8 chiamato a immergere in acqua la punta di una bacchetta sensibile in alluminio, il cui movimento attiva ogni volta una serie di intrecci musicali diversi modificati da un&#8217;avanzata tecnologia di rilevazione e attuazione acustica, progettata dal Centro Ricerche Musicali \u2013 CRM di Roma. Un&#8217;installazione che non \u00e8 mai la stessa ma che \u00e8 stata pensata per variare a seconda dello spazio e del momento in cui viene sollecitata. La serie di suoni ottenuti permette alle due vasche di dialogare musicalmente e di creare giochi nello spazio del cortile. Il progetto coinvolge nel suo spettro sensoriale anche la vista, grazie al contributo dell&#8217;accademia Rufa, che ha esteso cos\u00ec la collaborazione gi\u00e0 avviata con la Galleria Nazionale d\u2019Arte Moderna, occupandosi nello specifico dell&#8217;illuminazione dell&#8217;opera. Un esperimento poetico che rende tangibile e visibile l&#8217;immaterialit\u00e0 della musica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un&#8217;installazione multisensoriale, concepita in collaborazione con Rufa Il 6 febbraio la Galleria Nazionale d&#8217;Arte Moderna e contemporanea di Roma inaugura Forme immateriali del compositore Michelangelo Lupone, un&#8217;opera complessa che nasce dal connubio tra arte e musica, commissionata direttamente dalla GNAM per dialogare con l&#8217;architettura circostante ed essere inglobata nella collezione permanente del museo. Martina De&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/\" title=\"Read Michelangelo Lupone alla Gnam rende tangibile il suono\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":4762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[31,1641,1637],"tags":[],"class_list":["post-4761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-news","category-multimedia-arts-and-design","category-scultura-e-installazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Michelangelo Lupone alla Gnam rende tangibile il suono - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Michelangelo Lupone alla Gnam rende tangibile il suono - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Un&#8217;installazione multisensoriale, concepita in collaborazione con Rufa Il 6 febbraio la Galleria Nazionale d&#8217;Arte Moderna e contemporanea di Roma inaugura Forme immateriali del compositore Michelangelo Lupone, un&#8217;opera complessa che nasce dal connubio tra arte e musica, commissionata direttamente dalla GNAM per dialogare con l&#8217;architettura circostante ed essere inglobata nella collezione permanente del museo. Martina De... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-02T10:49:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-30T14:28:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/lupone-gnam.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/\",\"name\":\"Michelangelo Lupone alla Gnam rende tangibile il suono - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/lupone-gnam.jpg\",\"datePublished\":\"2015-02-02T10:49:30+00:00\",\"dateModified\":\"2020-08-30T14:28:58+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/lupone-gnam.jpg\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/lupone-gnam.jpg\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Michelangelo Lupone alla Gnam rende tangibile il suono\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/en\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Michelangelo Lupone alla Gnam rende tangibile il suono - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/","og_locale":"en_US","og_type":"article","og_title":"Michelangelo Lupone alla Gnam rende tangibile il suono - RUFA - Rome University of Fine Arts","og_description":"Un&#8217;installazione multisensoriale, concepita in collaborazione con Rufa Il 6 febbraio la Galleria Nazionale d&#8217;Arte Moderna e contemporanea di Roma inaugura Forme immateriali del compositore Michelangelo Lupone, un&#8217;opera complessa che nasce dal connubio tra arte e musica, commissionata direttamente dalla GNAM per dialogare con l&#8217;architettura circostante ed essere inglobata nella collezione permanente del museo. Martina De... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-02-02T10:49:30+00:00","article_modified_time":"2020-08-30T14:28:58+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/lupone-gnam.jpg","type":"image\/jpeg"}],"author":"rufa","twitter_misc":{"Written by":"rufa","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/","url":"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/","name":"Michelangelo Lupone alla Gnam rende tangibile il suono - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/lupone-gnam.jpg","datePublished":"2015-02-02T10:49:30+00:00","dateModified":"2020-08-30T14:28:58+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/lupone-gnam.jpg","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/02\/lupone-gnam.jpg","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/02\/02\/michelangelo-lupone-gnam-rende-tangibile-suono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"Michelangelo Lupone alla Gnam rende tangibile il suono"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/en\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/comments?post=4761"}],"version-history":[{"count":4,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4761\/revisions"}],"predecessor-version":[{"id":31829,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4761\/revisions\/31829"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media\/4762"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media?parent=4761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/categories?post=4761"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/tags?post=4761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}