


{"id":4732,"date":"2015-01-29T09:47:18","date_gmt":"2015-01-29T09:47:18","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=4732"},"modified":"2021-11-03T18:47:01","modified_gmt":"2021-11-03T17:47:01","slug":"direttore-rufa-microfoni-radio-colonna","status":"publish","type":"post","link":"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/","title":{"rendered":"Il direttore Rufa ai microfoni di radio Colonna"},"content":{"rendered":"<h3>Intervista a Fabio Mongelli che ricorda le linee guida dell\u2019accademia e ne racconta i successi<\/h3>\n<p>Parla Fabio Mongelli, direttore Rufa ai microfoni di radio Colonna. Il pretesto per questa breve intervista \u00e8 la partecipazione degli studenti al progetto Aracne, partecipazione che ha raggiunto ottimi risultati, tutti gli iscritti dell\u2019accademia sono, infatti, arrivati in finale. Da qui Mongelli traccia le idee alla base della programmazione Rufa: \u00abL\u2019attenzione alle tendenze generazionali e ai linguaggi della contemporaneit\u00e0 sono le linee guida del progetto culturale dell\u2019accademia\u00bb. Il direttore ricorda, poi, come esempi, il lavoro degli studenti condotto al Maxxi per la mostra Bellissima, sempre al Maxxi il video degli studenti per Corsaro: una performance firmata Elisabetta Benassi e conclude con gli interventi realizzati alla Gnam.<\/p>\n<p><a href=\"https:\/\/www.unirufa.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ascolta l&#8217;intervista<\/a>","protected":false},"excerpt":{"rendered":"<p>Intervista a Fabio Mongelli che ricorda le linee guida dell\u2019accademia e ne racconta i successi Parla Fabio Mongelli, direttore Rufa ai microfoni di radio Colonna. Il pretesto per questa breve intervista \u00e8 la partecipazione degli studenti al progetto Aracne, partecipazione che ha raggiunto ottimi risultati, tutti gli iscritti dell\u2019accademia sono, infatti, arrivati in finale. Da&#8230;  <a class=\"excerpt-read-more\" href=\"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/\" title=\"Read Il direttore Rufa ai microfoni di radio Colonna\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":4733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1629,31],"tags":[],"class_list":["post-4732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accademia","category-app-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il direttore Rufa ai microfoni di radio Colonna - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il direttore Rufa ai microfoni di radio Colonna - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Intervista a Fabio Mongelli che ricorda le linee guida dell\u2019accademia e ne racconta i successi Parla Fabio Mongelli, direttore Rufa ai microfoni di radio Colonna. Il pretesto per questa breve intervista \u00e8 la partecipazione degli studenti al progetto Aracne, partecipazione che ha raggiunto ottimi risultati, tutti gli iscritti dell\u2019accademia sono, infatti, arrivati in finale. Da... Find out more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-29T09:47:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-03T17:47:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/01\/fabio-mongelli.png\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/\",\"url\":\"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/\",\"name\":\"Il direttore Rufa ai microfoni di radio Colonna - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/3.66.171.122\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/01\/fabio-mongelli.png\",\"datePublished\":\"2015-01-29T09:47:18+00:00\",\"dateModified\":\"2021-11-03T17:47:01+00:00\",\"author\":{\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/#primaryimage\",\"url\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/01\/fabio-mongelli.png\",\"contentUrl\":\"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/01\/fabio-mongelli.png\",\"width\":480,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/3.66.171.122\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il direttore Rufa ai microfoni di radio Colonna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/3.66.171.122\/#website\",\"url\":\"https:\/\/3.66.171.122\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/3.66.171.122\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/3.66.171.122\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"http:\/\/3.66.171.122\/en\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il direttore Rufa ai microfoni di radio Colonna - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/","og_locale":"en_US","og_type":"article","og_title":"Il direttore Rufa ai microfoni di radio Colonna - RUFA - Rome University of Fine Arts","og_description":"Intervista a Fabio Mongelli che ricorda le linee guida dell\u2019accademia e ne racconta i successi Parla Fabio Mongelli, direttore Rufa ai microfoni di radio Colonna. Il pretesto per questa breve intervista \u00e8 la partecipazione degli studenti al progetto Aracne, partecipazione che ha raggiunto ottimi risultati, tutti gli iscritti dell\u2019accademia sono, infatti, arrivati in finale. Da... Find out more","og_url":"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2015-01-29T09:47:18+00:00","article_modified_time":"2021-11-03T17:47:01+00:00","og_image":[{"width":480,"height":300,"url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/01\/fabio-mongelli.png","type":"image\/png"}],"author":"rufa","twitter_misc":{"Written by":"rufa","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/","url":"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/","name":"Il direttore Rufa ai microfoni di radio Colonna - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/3.66.171.122\/#website"},"primaryImageOfPage":{"@id":"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/#primaryimage"},"image":{"@id":"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/#primaryimage"},"thumbnailUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/01\/fabio-mongelli.png","datePublished":"2015-01-29T09:47:18+00:00","dateModified":"2021-11-03T17:47:01+00:00","author":{"@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/#primaryimage","url":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/01\/fabio-mongelli.png","contentUrl":"http:\/\/3.66.171.122\/wp-content\/uploads\/2015\/01\/fabio-mongelli.png","width":480,"height":300},{"@type":"BreadcrumbList","@id":"http:\/\/3.66.171.122\/en\/2015\/01\/29\/direttore-rufa-microfoni-radio-colonna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3.66.171.122\/"},{"@type":"ListItem","position":2,"name":"Il direttore Rufa ai microfoni di radio Colonna"}]},{"@type":"WebSite","@id":"https:\/\/3.66.171.122\/#website","url":"https:\/\/3.66.171.122\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3.66.171.122\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/3.66.171.122\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"http:\/\/3.66.171.122\/en\/author\/rufa\/"}]}},"_links":{"self":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/comments?post=4732"}],"version-history":[{"count":7,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4732\/revisions"}],"predecessor-version":[{"id":55245,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/posts\/4732\/revisions\/55245"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media\/4733"}],"wp:attachment":[{"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/media?parent=4732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/categories?post=4732"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/3.66.171.122\/en\/wp-json\/wp\/v2\/tags?post=4732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}